{"id":12167,"date":"2015-11-18T08:37:53","date_gmt":"2015-11-18T08:37:53","guid":{"rendered":"https:\/\/chargingyourev.eu\/home-store\/"},"modified":"2024-02-21T12:18:33","modified_gmt":"2024-02-21T11:18:33","slug":"home-store","status":"publish","type":"page","link":"https:\/\/cirveproject.com\/es\/","title":{"rendered":"Home Cirve"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a041c70c2e0b .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a041c70c2e0b .cmsmasters_row_outer_parent { \n\tpadding-bottom: 0px; \n} \n\n#cmsmasters_row_6a041c70c2e0b .cmsmasters_row_inner.cmsmasters_row_fullwidth { \n\tpadding-left:0%; \n} \n#cmsmasters_row_6a041c70c2e0b .cmsmasters_row_inner.cmsmasters_row_fullwidth { \n\tpadding-right:0%; \n} \n \n#cmsmasters_row_6a041c70c308a .cmsmasters_row_outer_parent { \n\tpadding-top: 55px; \n} \n\n#cmsmasters_row_6a041c70c308a .cmsmasters_row_outer_parent { \n\tpadding-bottom: 65px; \n} \n\n \n#cmsmasters_icon_box_6a041c70c3c2e { \n\tborder-width:0px; \n\tcolor:#343434;\n\tbackground-color:#ffffff;\n} \n\n#cmsmasters_icon_box_6a041c70c3c2e:before, \n#cmsmasters_icon_box_6a041c70c3c2e .icon_box_heading:before { \n\tfont-size:130px; \n\tline-height:130px; \n\twidth:130px; \n\theight:130px; \n\tborder-width:0px; \n} \n\n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_heading_left, \n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_top, \n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left_top { \n\tpadding:30px 20px; } \n\n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_top:before { \n\ttop:30px;} \n\n#cmsmasters_icon_box_6a041c70c3c2e a:not(.cmsmasters_button), \n#cmsmasters_icon_box_6a041c70c3c2e a:not(.cmsmasters_button):hover, \n#cmsmasters_icon_box_6a041c70c3c2e h1, \n#cmsmasters_icon_box_6a041c70c3c2e h2, \n#cmsmasters_icon_box_6a041c70c3c2e h3, \n#cmsmasters_icon_box_6a041c70c3c2e h4, \n#cmsmasters_icon_box_6a041c70c3c2e h5, \n#cmsmasters_icon_box_6a041c70c3c2e h6 { \n\tcolor:#343434;} \n\n#cmsmasters_icon_box_6a041c70c3c2e a:not(.cmsmasters_button) { \n\n\ttext-decoration:underline;} \n\n#cmsmasters_icon_box_6a041c70c3c2e a:not(.cmsmasters_button):hover { \n\n\ttext-decoration:none;} \n\n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left, \n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left_top { \n\tpadding-left:95px; \n\tmargin-left:65px; \n\t} \n\n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left:before, \n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left_top:before { \n\tleft:-65px; \n\t} \n\n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left:before { \n\tmargin-top:-65px; \n\t} \n\n@media only screen and (max-width: 540px) {#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left { \n\tpadding-top:85px; \n\tmargin-top:65px; \n\tmargin-left:0px; \n\tmargin-right:0px; \n\tpadding-left:20px; \n\tpadding-right:20px; \n\tpadding-bottom:65px; \n\t} \n\n#cmsmasters_icon_box_6a041c70c3c2e.cmsmasters_icon_box_left:before { \n\ttop:-65px; \n\tleft:0px; \n\tright:0px; \n\tmargin:0 auto; \n\t} \n\n}#cmsmasters_icon_box_6a041c70c3c2e:before { \n\tbackground-image:url(https:\/\/cirveproject.com\/wp-content\/uploads\/2015\/11\/project.jpg); \n} \n \n#cmsmasters_divider_6a041c70c472e { \n\tborder-bottom-width:0px; \n\tborder-bottom-style:solid; \n\tpadding-top:10px; \n\tmargin-bottom:0px; \n} \n \n#cmsmasters_divider_6a041c70c47fb { \n\tborder-bottom-width:0px; \n\tborder-bottom-style:solid; \n\tpadding-top:-50px; \n\tmargin-bottom:-50px; \n} \n \n#cmsmasters_icon_box_6a041c70c4b9a { \n\tborder-width:0px; \n\tcolor:#343434;\n\tbackground-color:#ffffff;\n} \n\n#cmsmasters_icon_box_6a041c70c4b9a:before, \n#cmsmasters_icon_box_6a041c70c4b9a .icon_box_heading:before { \n\tfont-size:130px; \n\tline-height:130px; \n\twidth:130px; \n\theight:130px; \n\tborder-width:0px; \n} \n\n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_heading_left, \n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_top, \n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left_top { \n\tpadding:30px 20px; } \n\n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_top:before { \n\ttop:30px;} \n\n#cmsmasters_icon_box_6a041c70c4b9a a:not(.cmsmasters_button), \n#cmsmasters_icon_box_6a041c70c4b9a a:not(.cmsmasters_button):hover, \n#cmsmasters_icon_box_6a041c70c4b9a h1, \n#cmsmasters_icon_box_6a041c70c4b9a h2, \n#cmsmasters_icon_box_6a041c70c4b9a h3, \n#cmsmasters_icon_box_6a041c70c4b9a h4, \n#cmsmasters_icon_box_6a041c70c4b9a h5, \n#cmsmasters_icon_box_6a041c70c4b9a h6 { \n\tcolor:#343434;} \n\n#cmsmasters_icon_box_6a041c70c4b9a a:not(.cmsmasters_button) { \n\n\ttext-decoration:underline;} \n\n#cmsmasters_icon_box_6a041c70c4b9a a:not(.cmsmasters_button):hover { \n\n\ttext-decoration:none;} \n\n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left, \n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left_top { \n\tpadding-left:95px; \n\tmargin-left:65px; \n\t} \n\n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left:before, \n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left_top:before { \n\tleft:-65px; \n\t} \n\n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left:before { \n\tmargin-top:-65px; \n\t} \n\n@media only screen and (max-width: 540px) {#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left { \n\tpadding-top:85px; \n\tmargin-top:65px; \n\tmargin-left:0px; \n\tmargin-right:0px; \n\tpadding-left:20px; \n\tpadding-right:20px; \n\tpadding-bottom:65px; \n\t} \n\n#cmsmasters_icon_box_6a041c70c4b9a.cmsmasters_icon_box_left:before { \n\ttop:-65px; \n\tleft:0px; \n\tright:0px; \n\tmargin:0 auto; \n\t} \n\n}#cmsmasters_icon_box_6a041c70c4b9a:before { \n\tbackground-image:url(https:\/\/cirveproject.com\/wp-content\/uploads\/2015\/11\/partners.jpg); \n} \n \n#cmsmasters_divider_6a041c70c551a { \n\tborder-bottom-width:0px; \n\tborder-bottom-style:solid; \n\tpadding-top:10px; \n\tmargin-bottom:0px; \n} \n \n#cmsmasters_divider_6a041c70c57ef { \n\tborder-bottom-width:0px; \n\tborder-bottom-style:solid; \n\tpadding-top:-50px; \n\tmargin-bottom:-50px; \n} \n \n#cmsmasters_row_6a041c70c5856 { \n\tbackground-color:#385996;\n} \n\n#cmsmasters_row_6a041c70c5856 .cmsmasters_row_outer_parent { \n\tpadding-top: 60px; \n} \n\n#cmsmasters_row_6a041c70c5856 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 60px; \n} \n\n#cmsmasters_row_6a041c70c5856 .cmsmasters_row_inner.cmsmasters_row_fullwidth { \n\tpadding-left:3%; \n} \n#cmsmasters_row_6a041c70c5856 .cmsmasters_row_inner.cmsmasters_row_fullwidth { \n\tpadding-right:3%; \n} \n \n#cmsmasters_heading_6a041c70c5bad { \n\ttext-align:center; \n\tmargin-top:0px; \n\tmargin-bottom:0px; \n} \n\n#cmsmasters_heading_6a041c70c5bad .cmsmasters_heading { \n\ttext-align:center; \n} \n\n#cmsmasters_heading_6a041c70c5bad .cmsmasters_heading, #cmsmasters_heading_6a041c70c5bad .cmsmasters_heading a { \n\tfont-size:40px; \n\tfont-weight:300; \n\tfont-style:normal; \n} \n\n#cmsmasters_heading_6a041c70c5bad .cmsmasters_heading_divider { \n} \n\n \n#cmsmasters_row_6a041c70c5c79 { \n\tbackground-color:#f8f8f8;\n\tbackground-image: url(https:\/\/cirveproject.com\/wp-content\/uploads\/2016\/06\/02-1.jpg); \n\tbackground-position: top center; \n\tbackground-repeat: no-repeat; \n\tbackground-attachment: scroll; \n\tbackground-size: cover; \n} \n\n#cmsmasters_row_6a041c70c5c79 .cmsmasters_row_outer_parent { \n\tpadding-top: 50px; \n} \n\n#cmsmasters_row_6a041c70c5c79 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_counters_6a041c70c6b00 .cmsmasters_counter.counter_has_icon .cmsmasters_counter_inner, \n#cmsmasters_counters_6a041c70c6b00 .cmsmasters_counter.counter_has_icon .cmsmasters_counter_inner, #cmsmasters_counters_6a041c70c6b00 .cmsmasters_counter.counter_has_image .cmsmasters_counter_inner, #cmsmasters_counters_6a041c70c6b00.counters_type_horizontal .cmsmasters_counter.counter_has_icon .cmsmasters_counter_subtitle { \n\tpadding-top:130px; \n} \n\n#cmsmasters_counters_6a041c70c6b00.counters_type_vertical .cmsmasters_counter .cmsmasters_counter_inner:before { \n\tmargin-left:-60px; \n} \n\n#cmsmasters_counters_6a041c70c6b00.counters_type_horizontal .cmsmasters_counter .cmsmasters_counter_inner .cmsmasters_counter_counter_wrap { \n\tline-height:120px; \n} \n\n#cmsmasters_counters_6a041c70c6b00 .cmsmasters_counter .cmsmasters_counter_inner:before { \n\tfont-size:48px; \n\tline-height:120px; \n\twidth:120px; \n\theight:120px; \n\tborder-width:0px; \n\t-webkit-border-radius:50%; \n\tborder-radius:50%; \n} \n\n\n#cmsmasters_counter_6a041c70c6d0e .cmsmasters_counter_inner:before { \n} \n\n\n#cmsmasters_counter_6a041c70c6df0 .cmsmasters_counter_inner:before { \n} \n\n\n#cmsmasters_counter_6a041c70c6eab .cmsmasters_counter_inner:before { \n} \n\n\n#cmsmasters_counter_6a041c70c6f8e .cmsmasters_counter_inner:before { \n} \n\n \n#cmsmasters_row_6a041c70c7083 { \n\tbackground-image: url(https:\/\/cirveproject.com\/wp-content\/uploads\/2015\/11\/water-conservation.jpg); \n\tbackground-position: top center; \n\tbackground-repeat: no-repeat; \n\tbackground-attachment: scroll; \n\tbackground-size: cover; \n} \n\n#cmsmasters_row_6a041c70c7083 .cmsmasters_row_outer_parent { \n\tpadding-top: 100px; \n} \n\n#cmsmasters_row_6a041c70c7083 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 100px; \n} \n\n \n#cmsmasters_heading_6a041c70c7cb7 { \n\ttext-align:center; \n\tmargin-top:0px; \n\tmargin-bottom:-40px; \n} \n\n#cmsmasters_heading_6a041c70c7cb7 .cmsmasters_heading { \n\ttext-align:center; \n} \n\n#cmsmasters_heading_6a041c70c7cb7 .cmsmasters_heading, #cmsmasters_heading_6a041c70c7cb7 .cmsmasters_heading a { \n\tfont-size:42px; \n\tline-height:52px; \n\tfont-weight:500; \n\tfont-style:normal; \n\tcolor:#46c965;\n} \n\n#cmsmasters_heading_6a041c70c7cb7 .cmsmasters_heading_divider { \n} \n\n@media (max-width: 767px) {\n\n#cmsmasters_heading_6a041c70c7cb7 .cmsmasters_heading, #cmsmasters_heading_6a041c70c7cb7 .cmsmasters_heading a { \n\tfont-size:32px; \n\tline-height:42px; \n} \n\n} \n\n \n#cmsmasters_row_6a041c7102689 { \n\tbackground-image: url(https:\/\/cirveproject.com\/wp-content\/uploads\/2015\/11\/water-conservation.jpg); \n\tbackground-position: top center; \n\tbackground-repeat: no-repeat; \n\tbackground-attachment: scroll; \n\tbackground-size: cover; \n} \n\n#cmsmasters_row_6a041c7102689 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a041c7102689 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_row_6a041c71027f1 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a041c71027f1 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_row_6a041c7103c5d { \n\tbackground-color:#385996;\n} \n\n#cmsmasters_row_6a041c7103c5d .cmsmasters_row_outer_parent { \n\tpadding-top: 50px; \n} \n\n#cmsmasters_row_6a041c7103c5d .cmsmasters_row_outer_parent { \n\tpadding-bottom: 70px; \n} \n\n \n#cmsmasters_heading_6a041c71040cc { \n\ttext-align:center; \n\tmargin-top:0px; \n\tmargin-bottom:-40px; \n} \n\n#cmsmasters_heading_6a041c71040cc .cmsmasters_heading { \n\ttext-align:center; \n} \n\n#cmsmasters_heading_6a041c71040cc .cmsmasters_heading, #cmsmasters_heading_6a041c71040cc .cmsmasters_heading a { \n\tfont-size:42px; \n\tline-height:53px; \n\tfont-weight:500; \n\tfont-style:normal; \n\tcolor:#ffffff;\n} \n\n#cmsmasters_heading_6a041c71040cc .cmsmasters_heading_divider { \n} \n\n@media (max-width: 767px) {\n\n#cmsmasters_heading_6a041c71040cc .cmsmasters_heading, #cmsmasters_heading_6a041c71040cc .cmsmasters_heading a { \n\tfont-size:32px; \n\tline-height:42px; \n} \n\n} \n\n \n#cmsmasters_row_6a041c710415b .cmsmasters_row_outer_parent { \n\tpadding-top: 70px; \n} \n\n#cmsmasters_row_6a041c710415b .cmsmasters_row_outer_parent { \n\tpadding-bottom: 70px; \n} \n\n \n#cmsmasters_clients_6a041c71043dc .cmsmasters_clients_item { height:45px; line-height:45px; } \n#cmsmasters_clients_6a041c71043dc .cmsmasters_clients_item a { line-height:45px; } \n \n#cmsmasters_row_6a041c71061b1 .cmsmasters_row_outer_parent { \n\tpadding-top: 10px; \n} \n\n#cmsmasters_row_6a041c71061b1 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 100px; \n} \n\n \n#cmsmasters_clients_6a041c710633e .cmsmasters_clients_item { height:45px; line-height:45px; } \n#cmsmasters_clients_6a041c710633e .cmsmasters_clients_item a { line-height:45px; } \n \n#cmsmasters_row_6a041c710a4de .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a041c710a4de .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n<\/style><div id=\"cmsmasters_row_6a041c70c28c7\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c70c2e0b\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c70c2ef9\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c70c308a\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_homepage_icons cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_icon_box_6a041c70c3c2e\" class=\"cmsmasters_icon_box cmsmasters_icon_box_left box_icon_type_image \">\n<div class=\"icon_box_inner\">\n<h4 class=\"icon_box_heading\"><\/h4>\n<div class=\"icon_box_text\">\n<h4>\n<div id=\"cmsmasters_divider_6a041c70c472e\" class=\"cl\"><\/div><\/h4>\n<h4><span style=\"font-size: 13pt;\"><a href=\"https:\/\/cirveproject.com\/es\/sobre-cirve\/#project\" target=\"_blank\" rel=\"noopener noreferrer\">EL PROYECTO CIRVE<\/a><\/span><\/h4>\n<p>El Proyecto CIRVE nace para desplegar una red de 40 puntos de carga r\u00e1pida para veh\u00edculos el\u00e9ctricos que conecte la Pen\u00ednsula Ib\u00e9rica con el resto de pa\u00edses de la Uni\u00f3n Europea. Su objetivo es facilitar un modelo de negocio para instalar toda una malla de sistemas de recarga el\u00e9ctrica en la Red Trans Europea de Transporte (RTE-T).<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div id=\"cmsmasters_divider_6a041c70c47fb\" class=\"cl\"><\/div>\n\n<div id=\"cmsmasters_icon_box_6a041c70c4b9a\" class=\"cmsmasters_icon_box cmsmasters_icon_box_left box_icon_type_image \">\n<div class=\"icon_box_inner\">\n<h4 class=\"icon_box_heading\"><\/h4>\n<div class=\"icon_box_text\">\n<h4>\n<div id=\"cmsmasters_divider_6a041c70c551a\" class=\"cl\"><\/div><\/h4>\n<h4><span style=\"font-size: 13pt;\"><a href=\"https:\/\/cirveproject.com\/es\/sobre-cirve\/#socios\" target=\"_blank\" rel=\"noopener noreferrer\">SOCIOS<\/a><\/span><\/h4>\n<p>Son 8 las entidades de Espa\u00f1a, Portugal y Francia involucradas en el proyecto CIRVE. Debido a la complejidad de la introducci\u00f3n sostenible de un sistema europeo de electromovilidad, dichas empresas son l\u00edderes en los grupos interesados \u200b\u200brelevantes.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_text\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1TvBfu41DowwGIcqFpFgmK4PxT1p_oBk6\" width=\"100%\" height=\"480\"><\/iframe>\n<\/div>\n\n<div id=\"cmsmasters_divider_6a041c70c57ef\" class=\"cl\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c70c5856\" class=\"cmsmasters_row cmsmasters_color_scheme_second cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner cmsmasters_row_fullwidth\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n\n<div id=\"cmsmasters_heading_6a041c70c5bad\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Construir Corredores Ib\u00e9ricos de Recarga R\u00e1pida es nuestra Misi\u00f3n<\/h3>\n<\/div><div class=\"cmsmasters_text\">\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/tinyurl.com\/srykws6\" target=\"_blank\" rel=\"noopener noreferrer\">Encuentra aqu\u00ed la ubicaci\u00f3n de los puntos de recarga en la Pen\u00ednsula Ib\u00e9rica<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c70c5c79\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n \n<div id=\"cmsmasters_counters_6a041c70c6b00\" class=\"cmsmasters_counters counters_type_vertical\"><div class=\"cmsmasters_counter_wrap one_fourth\">\n<div id=\"cmsmasters_counter_6a041c70c6d0e\" class=\"cmsmasters_counter counter_has_icon\" data-percent=\"100\">\n<div class=\"cmsmasters_counter_inner cmsmasters-icon-flash-1\">\n<span class=\"cmsmasters_counter_counter_wrap\">\n<span class=\"cmsmasters_counter_prefix\"><\/span><span class=\"cmsmasters_counter_counter\">0<\/span><span class=\"cmsmasters_counter_suffix\">%<\/span>\n<\/span>\n<span class=\"cmsmasters_counter_title\">Objetivo<\/span>\n<\/div>\n<span class=\"cmsmasters_counter_subtitle\">Implantaci\u00f3n de 40 puntos de recarga r\u00e1pida en el Corredor Ib\u00e9rico<\/span>\n<\/div>\n<\/div><div class=\"cmsmasters_counter_wrap one_fourth\">\n<div id=\"cmsmasters_counter_6a041c70c6df0\" class=\"cmsmasters_counter counter_has_icon\" data-percent=\"100\">\n<div class=\"cmsmasters_counter_inner cmsmasters-icon-thumbs-up-1\">\n<span class=\"cmsmasters_counter_counter_wrap\">\n<span class=\"cmsmasters_counter_prefix\"><\/span><span class=\"cmsmasters_counter_counter\">0<\/span><span class=\"cmsmasters_counter_suffix\">%<\/span>\n<\/span>\n<span class=\"cmsmasters_counter_title\">Progreso<\/span>\n<\/div>\n<span class=\"cmsmasters_counter_subtitle\">Evoluci\u00f3n del proyecto CIRVE a d\u00eda de hoy<\/span>\n<\/div>\n<\/div><div class=\"cmsmasters_counter_wrap one_fourth\">\n<div id=\"cmsmasters_counter_6a041c70c6eab\" class=\"cmsmasters_counter counter_has_icon\" data-percent=\"0\">\n<div class=\"cmsmasters_counter_inner cmsmasters-icon-tools\">\n<span class=\"cmsmasters_counter_counter_wrap\">\n<span class=\"cmsmasters_counter_prefix\"><\/span><span class=\"cmsmasters_counter_counter\">0<\/span><span class=\"cmsmasters_counter_suffix\">%<\/span>\n<\/span>\n<span class=\"cmsmasters_counter_title\">A conseguir<\/span>\n<\/div>\n<span class=\"cmsmasters_counter_subtitle\">Pendiente de instalaci\u00f3n<\/span>\n<\/div>\n<\/div><div class=\"cmsmasters_counter_wrap one_fourth\">\n<div id=\"cmsmasters_counter_6a041c70c6f8e\" class=\"cmsmasters_counter counter_has_icon\" data-percent=\"100\">\n<div class=\"cmsmasters_counter_inner cmsmasters-icon-spinner\">\n<span class=\"cmsmasters_counter_counter_wrap\">\n<span class=\"cmsmasters_counter_prefix\"><\/span><span class=\"cmsmasters_counter_counter\">0<\/span><span class=\"cmsmasters_counter_suffix\">%<\/span>\n<\/span>\n<span class=\"cmsmasters_counter_title\">Reducci\u00f3n de CO<sub>2<\/sub><\/span>\n<\/div>\n<span class=\"cmsmasters_counter_subtitle\">Del objetivo final del proyecto<\/span>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c70c7083\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_latest_news cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n\n<div id=\"cmsmasters_heading_6a041c70c7cb7\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h1 class=\"cmsmasters_heading\">Noticias<\/h1>\n<\/div>\n<div class=\"cmsmasters_posts_slider post\" >\r\n\t\t<script type=\"text\/javascript\">\r\n\t\t\tjQuery(document).ready(function () { \r\n\t\t\t\tvar container = jQuery('.cmsmasters_slider_6a041c70c8368');\r\n\t\t\t\t\tcontainerWidth = container.width(), \r\n\t\t\t\t\tfirstPost = container.find('article'), \r\n\t\t\t\t\tpostMinWidth = Number(firstPost.css('minWidth').replace('px', '')), \r\n\t\t\t\t\tpostThreeColumns = (postMinWidth * 4) - 1;\r\n\t\t\t\t\tpostTwoColumns = (postMinWidth * 3) - 1;\r\n\t\t\t\t\tpostOneColumns = (postMinWidth * 2) - 1; \r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\tjQuery('.cmsmasters_slider_6a041c70c8368').owlCarousel( {\r\n\t\t\t\t\titems : 3, \r\n\t\t\t\t\titemsDesktop : false,\r\n\t\t\t\t\titemsDesktopSmall : [postThreeColumns,3], \r\n\t\t\t\t\titemsTablet : [postTwoColumns,2], \r\n\t\t\t\t\titemsMobile : [postOneColumns,1], \r\n\t\t\t\t\ttransitionStyle : false, \r\n\t\t\t\t\trewindNav : true, \r\n\t\t\t\t\tslideSpeed : 200, \r\n\t\t\t\t\tpaginationSpeed : 800, \r\n\t\t\t\t\trewindSpeed : 1000, autoPlay : 5000, stopOnHover : true, \r\n\t\t\t\t\tautoHeight : true, \r\n\t\t\t\t\taddClassActive : true, \r\n\t\t\t\t\tresponsiveBaseWidth : '.cmsmasters_slider_6a041c70c8368', \r\n\t\t\t\t\tpagination : false, \r\n\t\t\t\t\tnavigation : true, \r\n\t\t\t\t\tnavigationText : [ \"<span class=\\\"cmsmasters_prev_arrow\\\"><span><\/span><\/span>\", \"<span class=\\\"cmsmasters_next_arrow\\\"><span><\/span><\/span>\" ] \r\n\t\t\t\t} );\r\n\t\t\t} );\r\n\t\t<\/script>\r\n\t\t<div id=\"cmsmasters_owl_carousel_6a041c70c8368\" class=\"cmsmasters_owl_slider cmsmasters_slider_6a041c70c8368\"><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13441\" class=\"cmsmasters_slider_post post-13441 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-interoperabilidad tag-movilidad-electrica tag-proyecto-cirve-es tag-red-transeuropea-de-transporte-es\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n-Proyecto-Cirve-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\" title=\"Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/\" title=\"Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"septiembre 16, 2021\">Sep 16, 2021<\/abbr><abbr class=\"dn date updated\" title=\"septiembre 16, 2021\">septiembre 16, 2021<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13441); return false;\" id=\"cmsmastersLike-13441\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/#respond\" title=\"Comment on Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/\">Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Ha demostrado que el despliegue de infraestructuras de carga de acceso p\u00fablico es operativo, interoperable y eficiente La sede central...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12999\" class=\"cmsmasters_slider_post post-12999 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-ciudad-del-transporte-de-murcia tag-gic-es tag-proyecto-europeo-cirve tag-recarga-rapida-para-vehiculos-electricos\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2020\/01\/punto-carga-Murcia-Veh\u00edculo-El\u00e9ctrico_CIRVE-project_-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\" title=\"La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/\" title=\"La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"enero 7, 2020\">Ene 07, 2020<\/abbr><abbr class=\"dn date updated\" title=\"enero 7, 2020\">enero 7, 2020<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12999); return false;\" id=\"cmsmastersLike-12999\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/#respond\" title=\"Comment on La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/\">La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Es v\u00e1lido para todos los modelos y costar\u00e1 0,45 euros el kw, que se pagar\u00e1n a trav\u00e9s de una app...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12984\" class=\"cmsmasters_slider_post post-12984 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-cirve tag-endesa-es tag-galp tag-movilidad tag-puntos-de-carga-rapida-vehiculo-electrico\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2019\/02\/Endesa-Inauguracion-Isla-Energia-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\" title=\"Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/endesa-inaugura-punto-carga-rapida\/\" title=\"Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"febrero 26, 2019\">Feb 26, 2019<\/abbr><abbr class=\"dn date updated\" title=\"febrero 28, 2019\">febrero 28, 2019<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12984); return false;\" id=\"cmsmastersLike-12984\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/endesa-inaugura-punto-carga-rapida\/#respond\" title=\"Comment on Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/endesa-inaugura-punto-carga-rapida\/\">Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Endesa y Galp han llegado a un acuerdo para instalar 5 puntos de carga r\u00e1pida en estaciones de servicio de...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/endesa-inaugura-punto-carga-rapida\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12922\" class=\"cmsmasters_slider_post post-12922 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-euskotren tag-ibil tag-movilidad-electrica tag-vehiculo-electrico\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/12\/euskotren_IBIL-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\" title=\"Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/euskotren-movilidad-electrica-ibil\/\" title=\"Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"diciembre 31, 2018\">Dic 31, 2018<\/abbr><abbr class=\"dn date updated\" title=\"diciembre 31, 2018\">diciembre 31, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12922); return false;\" id=\"cmsmastersLike-12922\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/euskotren-movilidad-electrica-ibil\/#respond\" title=\"Comment on Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/euskotren-movilidad-electrica-ibil\/\">Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>IBIL, empresa l\u00edder en infraestructura, tecnolog\u00eda y servicios para la recarga de veh\u00edculos el\u00e9ctricos, ha sido la encargada de instalar...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/euskotren-movilidad-electrica-ibil\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12917\" class=\"cmsmasters_slider_post post-12917 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-bilbao tag-coche-electrico tag-ibil tag-puntos-de-carga-rapida-vehiculo-electrico-bilbao\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/12\/IBIL-pone-en-funcionamiento-su-tercer-punto-de-carga-r\u00e1pida-en-la-Avenida-de-Sabino-Arana-Bilbao-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\" title=\"IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-tercer-punto-carga-rapida-bilbao\/\" title=\"IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"diciembre 11, 2018\">Dic 11, 2018<\/abbr><abbr class=\"dn date updated\" title=\"diciembre 11, 2018\">diciembre 11, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12917); return false;\" id=\"cmsmastersLike-12917\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/ibil-tercer-punto-carga-rapida-bilbao\/#respond\" title=\"Comment on IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-tercer-punto-carga-rapida-bilbao\/\">IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Es un servicio imprescindible para todos los veh\u00edculos el\u00e9ctricos del \u00e1rea metropolitana de Bilbao y Bilbao IBIL, empresa especializada en...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/ibil-tercer-punto-carga-rapida-bilbao\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12912\" class=\"cmsmasters_slider_post post-12912 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-endesa tag-movilidad-sostenible tag-puntos-de-recarga-vehiculo tag-vehiculo-electrico\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/11\/Endesa-instalara-puntos-de-recarga-vehiculo-electrico-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\" title=\"Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/endesa-puntos-recarga-vehiculos-electricos\/\" title=\"Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"noviembre 19, 2018\">Nov 19, 2018<\/abbr><abbr class=\"dn date updated\" title=\"noviembre 19, 2018\">noviembre 19, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12912); return false;\" id=\"cmsmastersLike-12912\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/endesa-puntos-recarga-vehiculos-electricos\/#respond\" title=\"Comment on Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/endesa-puntos-recarga-vehiculos-electricos\/\">Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Durante el periodo del plan, Endesa X tiene previsto instalar m\u00e1s de 8.500 puntos de acceso p\u00fablico y\u00a0alrededor de 100.000...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/endesa-puntos-recarga-vehiculos-electricos\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12902\" class=\"cmsmasters_slider_post post-12902 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-ibil tag-proyecto-cirve tag-recarga-rapida tag-vehiculo-electrico\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/10\/IBIL-puntos-de-recarga-r\u00e1pida_CIRVE-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"IBIL pone en marcha dos nuevos puntos de recarga r\u00e1pida dentro del proyecto CIRVE en Burgos e Ir\u00fan\" title=\"IBIL pone en marcha dos nuevos puntos de recarga r\u00e1pida dentro del proyecto CIRVE en Burgos e Ir\u00fan\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-nuevos-puntos-recarga-rapida-proyecto-cirve\/\" title=\"IBIL pone en marcha dos nuevos puntos de recarga r\u00e1pida dentro del proyecto CIRVE en Burgos e Ir\u00fan\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"octubre 23, 2018\">Oct 23, 2018<\/abbr><abbr class=\"dn date updated\" title=\"noviembre 19, 2018\">noviembre 19, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12902); return false;\" id=\"cmsmastersLike-12902\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/ibil-nuevos-puntos-recarga-rapida-proyecto-cirve\/#respond\" title=\"Comment on IBIL pone en marcha dos nuevos puntos de recarga r\u00e1pida dentro del proyecto CIRVE en Burgos e Ir\u00fan\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-nuevos-puntos-recarga-rapida-proyecto-cirve\/\">IBIL pone en marcha dos nuevos puntos de recarga r\u00e1pida dentro del proyecto CIRVE en Burgos e Ir\u00fan<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Este proyecto conectar\u00e1 a Espa\u00f1a mediante instalaciones de carga r\u00e1pida con Francia y Portugal a trav\u00e9s de los corredores Atl\u00e1ntico...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/ibil-nuevos-puntos-recarga-rapida-proyecto-cirve\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12897\" class=\"cmsmasters_slider_post post-12897 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-puntos-de-carga-vehiculo-electrico tag-vehiculo-electrico\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/10\/Arturo-P\u00e9rez-de-Lucia-en-jornadas-organizadas-por-AEESCAM-y-AEVECAR_AEDIVE_CIRVE-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"Veh\u00edculo el\u00e9ctrico y estaciones de servicio: \u201cSi Mahoma no va a la monta\u00f1a, nos buscaremos otras monta\u00f1as\u201d\" title=\"Veh\u00edculo el\u00e9ctrico y estaciones de servicio: \u201cSi Mahoma no va a la monta\u00f1a, nos buscaremos otras monta\u00f1as\u201d\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/puntos-carga-vehiculo-electrico-estaciones-servicio\/\" title=\"Veh\u00edculo el\u00e9ctrico y estaciones de servicio: \u201cSi Mahoma no va a la monta\u00f1a, nos buscaremos otras monta\u00f1as\u201d\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"octubre 22, 2018\">Oct 22, 2018<\/abbr><abbr class=\"dn date updated\" title=\"octubre 22, 2018\">octubre 22, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12897); return false;\" id=\"cmsmastersLike-12897\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/puntos-carga-vehiculo-electrico-estaciones-servicio\/#respond\" title=\"Comment on Veh\u00edculo el\u00e9ctrico y estaciones de servicio: \u201cSi Mahoma no va a la monta\u00f1a, nos buscaremos otras monta\u00f1as\u201d\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/puntos-carga-vehiculo-electrico-estaciones-servicio\/\">Veh\u00edculo el\u00e9ctrico y estaciones de servicio: \u201cSi Mahoma no va a la monta\u00f1a, nos buscaremos otras monta\u00f1as\u201d<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Es fundamental que la recarga r\u00e1pida y ultrarr\u00e1pida tengan un justiprecio para que exista un modelo de negocio para las...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/puntos-carga-vehiculo-electrico-estaciones-servicio\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12890\" class=\"cmsmasters_slider_post post-12890 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-eficiencia-energetica tag-gestor-de-carga tag-movilidad-electrica tag-vehiculos-electricos\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/10\/eliminaci\u00f3n-gestor-de-carga_movilidad-el\u00e9ctrica-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"El Parlamento debe asumir ahora su responsabilidad en el impulso a la movilidad el\u00e9ctrica, reclama AEDIVE\" title=\"El Parlamento debe asumir ahora su responsabilidad en el impulso a la movilidad el\u00e9ctrica, reclama AEDIVE\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/parlamento-responsabilidad-impulso-movilidad-electrica\/\" title=\"El Parlamento debe asumir ahora su responsabilidad en el impulso a la movilidad el\u00e9ctrica, reclama AEDIVE\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"octubre 8, 2018\">Oct 08, 2018<\/abbr><abbr class=\"dn date updated\" title=\"octubre 8, 2018\">octubre 8, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12890); return false;\" id=\"cmsmastersLike-12890\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/parlamento-responsabilidad-impulso-movilidad-electrica\/#respond\" title=\"Comment on El Parlamento debe asumir ahora su responsabilidad en el impulso a la movilidad el\u00e9ctrica, reclama AEDIVE\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/parlamento-responsabilidad-impulso-movilidad-electrica\/\">El Parlamento debe asumir ahora su responsabilidad en el impulso a la movilidad el\u00e9ctrica, reclama AEDIVE<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>AEDIVE trabaja ya con las Administraciones para complementar este Real Decreto y acompasarlo con incentivos fiscales a la compra y...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/parlamento-responsabilidad-impulso-movilidad-electrica\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12885\" class=\"cmsmasters_slider_post post-12885 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-cargar-vehiculos-electricos tag-expoelectric-2018 tag-ibil\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/10\/Ibil-en-Expoelectric_CIRVE-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"IBIL gestiona en exclusiva la recarga de los veh\u00edculos de Expoelectric 2018\" title=\"IBIL gestiona en exclusiva la recarga de los veh\u00edculos de Expoelectric 2018\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-expoelectric-2018\/\" title=\"IBIL gestiona en exclusiva la recarga de los veh\u00edculos de Expoelectric 2018\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"octubre 4, 2018\">Oct 04, 2018<\/abbr><abbr class=\"dn date updated\" title=\"octubre 4, 2018\">octubre 4, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12885); return false;\" id=\"cmsmastersLike-12885\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/ibil-expoelectric-2018\/#respond\" title=\"Comment on IBIL gestiona en exclusiva la recarga de los veh\u00edculos de Expoelectric 2018\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-expoelectric-2018\/\">IBIL gestiona en exclusiva la recarga de los veh\u00edculos de Expoelectric 2018<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>La compa\u00f1\u00eda proporciona la recarga a los veh\u00edculos el\u00e9ctricos presentes en el evento m\u00e1s importante del sur de Europa, con...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/ibil-expoelectric-2018\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12872\" class=\"cmsmasters_slider_post post-12872 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-ayuntamiento-de-vitoria-gasteiz tag-ibil tag-movilidad-sostenible tag-recarga-de-vehiculos-electricos tag-vehiculos-electricos-para-empresas\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/09\/punto-de-carga-IBIL_CIRVE-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"IBIL colabora con el Ayuntamiento de Vitoria-Gasteiz en la campa\u00f1a de pruebas de veh\u00edculos el\u00e9ctricos para empresas\" title=\"IBIL colabora con el Ayuntamiento de Vitoria-Gasteiz en la campa\u00f1a de pruebas de veh\u00edculos el\u00e9ctricos para empresas\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-colabora-con-ayuntamiento-vitoria-gasteiz-pruebas-vehiculos-electricos-empresas\/\" title=\"IBIL colabora con el Ayuntamiento de Vitoria-Gasteiz en la campa\u00f1a de pruebas de veh\u00edculos el\u00e9ctricos para empresas\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"septiembre 27, 2018\">Sep 27, 2018<\/abbr><abbr class=\"dn date updated\" title=\"septiembre 27, 2018\">septiembre 27, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12872); return false;\" id=\"cmsmastersLike-12872\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/ibil-colabora-con-ayuntamiento-vitoria-gasteiz-pruebas-vehiculos-electricos-empresas\/#respond\" title=\"Comment on IBIL colabora con el Ayuntamiento de Vitoria-Gasteiz en la campa\u00f1a de pruebas de veh\u00edculos el\u00e9ctricos para empresas\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/ibil-colabora-con-ayuntamiento-vitoria-gasteiz-pruebas-vehiculos-electricos-empresas\/\">IBIL colabora con el Ayuntamiento de Vitoria-Gasteiz en la campa\u00f1a de pruebas de veh\u00edculos el\u00e9ctricos para empresas<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Dentro del Plan de Movilidad Sostenible y Espacio P\u00fablico, el Ayuntamiento de Vitoria-Gasteiz ha presentado hoy una campa\u00f1a de prueba...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/ibil-colabora-con-ayuntamiento-vitoria-gasteiz-pruebas-vehiculos-electricos-empresas\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div>\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-12863\" class=\"cmsmasters_slider_post post-12863 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es tag-ahorramas tag-ahorramas-punto-de-recarga-vehiculos-electricos tag-edp tag-recarga-electricos\">\r\n\t<div class=\"cmsmasters_slider_post_outer\">\r\n\t<div class=\"cmsmasters_slider_post_date_img_wrap\"><figure class=\"cmsmasters_img_rollover_wrap preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"445\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/09\/punto-de-recarga-en-Ahorramas-860x445.jpg\" class=\"full-width wp-post-image\" alt=\"Ahorramas inaugura una nueva tienda en Madrid con un punto de recarga para veh\u00edculos el\u00e9ctricos\" title=\"Ahorramas inaugura una nueva tienda en Madrid con un punto de recarga para veh\u00edculos el\u00e9ctricos\" \/><div class=\"cmsmasters_no_rollover\"><a href=\"https:\/\/cirveproject.com\/es\/ahorramas-nueva-tienda-madrid-punto-recarga-vehiculos-electricos\/\" title=\"Ahorramas inaugura una nueva tienda en Madrid con un punto de recarga para veh\u00edculos el\u00e9ctricos\" class=\"cmsmasters_open_link cmsmasters_theme_icon_image\"><\/a><\/div><\/figure><div class=\"cmsmasters_slider_post_date_top_meta_wrap\"><span class=\"cmsmasters_slider_post_date\"><abbr class=\"published\" title=\"septiembre 25, 2018\">Sep 25, 2018<\/abbr><abbr class=\"dn date updated\" title=\"septiembre 25, 2018\">septiembre 25, 2018<\/abbr><\/span><div class=\"cmsmasters_slider_post_social_wrap\"><span class=\"cmsmasters_likes cmsmasters_slider_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(12863); return false;\" id=\"cmsmastersLike-12863\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_comments cmsmasters_slider_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/es\/ahorramas-nueva-tienda-madrid-punto-recarga-vehiculos-electricos\/#respond\" title=\"Comment on Ahorramas inaugura una nueva tienda en Madrid con un punto de recarga para veh\u00edculos el\u00e9ctricos\"><span>0<\/span><\/a><\/span><\/div><\/div><\/div><div class=\"cmsmasters_slider_post_inner\"><header class=\"cmsmasters_slider_post_header entry-header\"><h3 class=\"cmsmasters_slider_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/es\/ahorramas-nueva-tienda-madrid-punto-recarga-vehiculos-electricos\/\">Ahorramas inaugura una nueva tienda en Madrid con un punto de recarga para veh\u00edculos el\u00e9ctricos<\/a><\/h3><\/header><div class=\"cmsmasters_slider_post_cont_info entry-meta\"><span class=\"cmsmasters_slider_post_category\">In <a href=\"https:\/\/cirveproject.com\/es\/category\/cirve-es\/\" class=\"cmsmasters_cat_color cmsmasters_cat_81\" rel=\"category tag\">Cirve ES<\/a><\/span><\/div><div class=\"cmsmasters_slider_post_content entry-content\">\n<p>Es el segundo punto de la cadena en la comunidad madrile\u00f1a, fruto del acuerdo con la energ\u00e9tica EDP Los clientes...<\/p>\n<\/div>\n<footer class=\"cmsmasters_slider_post_footer entry-meta\"><a class=\"button cmsmasters_slider_post_read_more\" href=\"https:\/\/cirveproject.com\/es\/ahorramas-nueva-tienda-madrid-punto-recarga-vehiculos-electricos\/\">Read More<\/a><\/footer><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c7102689\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_third\">\n<\/div>\n<div class=\"cmsmasters_column one_first\">\n<\/div>\n<div class=\"cmsmasters_column one_third\">\n<\/div>\n<div class=\"cmsmasters_column one_third\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c71027f1\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div id=\"cmsmasters_video_wrap_6a041c7103b7a\" class=\"cmsmasters_video_wrap\">\n<iframe loading=\"lazy\" title=\"Presentaci\u00f3n el Proyecto Europeo CIRVE - Corredores Ib\u00e9ricos de Infraestructura de Recarga R\u00e1pida\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/hlie4IfwxCw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c7103c5d\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n\n<div id=\"cmsmasters_heading_6a041c71040cc\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_center\">\n\t<h3 class=\"cmsmasters_heading\">Socios<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c710415b\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n\n<div class=\"cmsmasters_clients_grid_wrap\">\n<div id=\"cmsmasters_clients_6a041c71043dc\" class=\"cmsmasters_clients_grid clients_four\">\n<div class=\"cmsmasters_clients_items slides\">\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"http:\/\/aedive.es\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2021\/09\/Logo-AEDIVE.jpg\" alt=\"Name\" title=\"Name\" \/><\/a>\n<\/div>\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"https:\/\/www.ceiia.com\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2015\/11\/CEIIA.jpg\" alt=\"CEIIA\" title=\"CEIIA\" \/><\/a>\n<\/div>\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"http:\/\/www.edpenergia.es\/es\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2021\/09\/EDP.jpg\" alt=\"Name\" title=\"Name\" \/><\/a>\n<\/div>\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"https:\/\/www.endesax.com\/es\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2021\/09\/Endesa_X.jpg\" alt=\"endesa\" title=\"endesa\" \/><\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c71061b1\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n\n<div class=\"cmsmasters_clients_grid_wrap\">\n<div id=\"cmsmasters_clients_6a041c710633e\" class=\"cmsmasters_clients_grid clients_four\">\n<div class=\"cmsmasters_clients_items slides\">\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"http:\/\/www.recargagic.com\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2015\/11\/GIC-Logo.jpg\" alt=\"Name\" title=\"Name\" \/><\/a>\n<\/div>\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"https:\/\/www.iberdrola.es\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2017\/08\/IBERDROLA_v2.png\" alt=\"IBERDROLA Logo\" title=\"IBERDROLA Logo\" \/><\/a>\n<\/div>\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"https:\/\/www.ibil.es\/index.php\/es\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2020\/03\/IBIL.jpg\" alt=\"Name\" title=\"Name\" \/><\/a>\n<\/div>\n<div class=\"cmsmasters_clients_item item\">\n<a href=\"http:\/\/www.renault.es\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2021\/09\/MobilizeRenault.jpg\" alt=\"RENAULT Logo\" title=\"RENAULT Logo\" \/><\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a041c710a4de\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home Cirve - CIRVE Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cirveproject.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home Cirve - CIRVE Project\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cirveproject.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"CIRVE Project\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T11:18:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CIRVEproject\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cirveproject.com\/es\/\",\"url\":\"https:\/\/cirveproject.com\/es\/\",\"name\":\"Home Cirve - CIRVE Project\",\"isPartOf\":{\"@id\":\"https:\/\/cirveproject.com\/#website\"},\"datePublished\":\"2015-11-18T08:37:53+00:00\",\"dateModified\":\"2024-02-21T11:18:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cirveproject.com\/es\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cirveproject.com\/es\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cirveproject.com\/es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cirveproject.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home Cirve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cirveproject.com\/#website\",\"url\":\"https:\/\/cirveproject.com\/\",\"name\":\"CIRVE Project\",\"description\":\"Connecting the Iberian Peninsula with the other countries of the European Union is the mission of the CIRVE Project, whose acronym stands for \u201cIberian Corridors of Rapid Recharging Infrastructure for Electric Vehicles\u201d.\",\"publisher\":{\"@id\":\"https:\/\/cirveproject.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cirveproject.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cirveproject.com\/#organization\",\"name\":\"CIRVE Project\",\"url\":\"https:\/\/cirveproject.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png\",\"contentUrl\":\"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png\",\"width\":190,\"height\":65,\"caption\":\"CIRVE Project\"},\"image\":{\"@id\":\"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/CIRVEproject\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home Cirve - CIRVE Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cirveproject.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Home Cirve - CIRVE Project","og_url":"https:\/\/cirveproject.com\/es\/","og_site_name":"CIRVE Project","article_modified_time":"2024-02-21T11:18:33+00:00","twitter_card":"summary_large_image","twitter_site":"@CIRVEproject","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cirveproject.com\/es\/","url":"https:\/\/cirveproject.com\/es\/","name":"Home Cirve - CIRVE Project","isPartOf":{"@id":"https:\/\/cirveproject.com\/#website"},"datePublished":"2015-11-18T08:37:53+00:00","dateModified":"2024-02-21T11:18:33+00:00","breadcrumb":{"@id":"https:\/\/cirveproject.com\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cirveproject.com\/es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cirveproject.com\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cirveproject.com\/es\/"},{"@type":"ListItem","position":2,"name":"Home Cirve"}]},{"@type":"WebSite","@id":"https:\/\/cirveproject.com\/#website","url":"https:\/\/cirveproject.com\/","name":"CIRVE Project","description":"Connecting the Iberian Peninsula with the other countries of the European Union is the mission of the CIRVE Project, whose acronym stands for \u201cIberian Corridors of Rapid Recharging Infrastructure for Electric Vehicles\u201d.","publisher":{"@id":"https:\/\/cirveproject.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cirveproject.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cirveproject.com\/#organization","name":"CIRVE Project","url":"https:\/\/cirveproject.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/","url":"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png","contentUrl":"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png","width":190,"height":65,"caption":"CIRVE Project"},"image":{"@id":"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/CIRVEproject"]}]}},"_links":{"self":[{"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/pages\/12167"}],"collection":[{"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/comments?post=12167"}],"version-history":[{"count":79,"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/pages\/12167\/revisions"}],"predecessor-version":[{"id":13714,"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/pages\/12167\/revisions\/13714"}],"wp:attachment":[{"href":"https:\/\/cirveproject.com\/es\/wp-json\/wp\/v2\/media?parent=12167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}