{"id":13146,"date":"2017-06-12T08:58:26","date_gmt":"2017-06-12T08:58:26","guid":{"rendered":"http:\/\/cirveproject.com\/noticias\/"},"modified":"2020-02-24T15:59:03","modified_gmt":"2020-02-24T15:59:03","slug":"nouvelles","status":"publish","type":"page","link":"https:\/\/cirveproject.com\/fr\/nouvelles\/","title":{"rendered":"Nouvelles"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a0426876d140 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a0426876d140 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n<\/style><div id=\"cmsmasters_row_6a0426876d140\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_wrap_blog entry-summary\" id=\"blog_6a0426876d74d\"><script type=\"text\/javascript\">\r\njQuery(document).ready(function () {\r\n\t(function ($) {\r\n\t\tif ($('#blog_6a0426876d74d').find('article').length == '0') {\r\n\t\t\treturn false;\r\n\t\t}\r\n\t\t\r\n\t\t\r\n\t\tstartBlog( \r\n\t\t\t'6a0426876d74d', \r\n\t\t\t'columns', \r\n\t\t\t'grid', \r\n\t\t\t'https:\/\/cirveproject.com\/wp-content\/plugins\/cmsmasters-content-composer\/', \r\n\t\t\t'date', \r\n\t\t\t'DESC', \r\n\t\t\t'6', \r\n\t\t\t'cirve-es-fr', \r\n\t\t\t'date,categories,author,comments,likes,more' \r\n\t\t);\r\n\t} )(jQuery);\r\n} );\r\n<\/script>\r\n<div class=\"blog columns grid cmsmasters_2\">\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13439\" class=\"cmsmasters_post_masonry post-13439 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es-fr tag-interoperabilidad-fr tag-movilidad-electrica-fr tag-proyecto-cirve-fr tag-red-transeuropea-de-transporte-fr\" data-category=\"cirve-es-fr\">\r\n\t<div class=\"cmsmasters_post_cont\">\r\n\t\t<figure class=\"cmsmasters_img_wrap\"><a href=\"https:\/\/cirveproject.com\/fr\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/\" title=\"Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\" class=\"cmsmasters_img_link preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"360\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n-Proyecto-Cirve-580x360.jpg\" class=\"full-width wp-post-image\" alt=\"Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\" title=\"Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\" \/><\/a><\/figure><div class=\"cmsmasters_post_cont_wrapper\"><div class=\"cmsmasters_post_info entry-meta\"><span class=\"cmsmasters_post_date\">On <abbr class=\"published\" title=\"septembre 16, 2021\"><span class=\"cmsmasters_day_mon\">septembre 16<\/span>, <span class=\"cmsmasters_year\">2021<\/span><\/abbr><abbr class=\"dn date updated\" title=\"septembre 16, 2021\">septembre 16, 2021<\/abbr><\/span><div class=\"cmsmasters_post_meta_info\"><span class=\"cmsmasters_comments cmsmasters_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/fr\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/#respond\" title=\"Comment on Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_likes cmsmasters_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13439); return false;\" id=\"cmsmastersLike-13439\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><\/div><\/div><div class=\"cmsmasters_post_info_bottom entry-meta\"><header class=\"cmsmasters_post_header entry-header\"><h3 class=\"cmsmasters_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/fr\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/\">Interoperabilidad y conexi\u00f3n de Espa\u00f1a con Francia y Portugal, claves del Proyecto Europeo CIRVE<\/a><\/h3><\/header><div class=\"cmsmasters_post_cont_info entry-meta\"><span class=\"cmsmasters_post_category\"><span>In<\/span><a href=\"https:\/\/cirveproject.com\/fr\/category\/cirve-es-fr\/\" class=\"cmsmasters_cat_color cmsmasters_cat_143\" rel=\"category tag\">Cirve ES<\/a><\/span><span class=\"cmsmasters_post_author\"><span>By<\/span><a href=\"https:\/\/cirveproject.com\/fr\/author\/aorenga_u8k3ghf9\/\" title=\"Posts by IMEDIA\" class=\"vcard author\"><span class=\"fn\" rel=\"author\">IMEDIA<\/span><\/a><\/span><\/div><div class=\"cmsmasters_post_content entry-content\">\n<p>Ha demostrado que el despliegue de infraestructuras de carga de acceso p\u00fablico es operativo, interoperable y eficiente La sede central...<\/p>\n<\/div>\n<footer class=\"cmsmasters_post_footer entry-meta\"><a class=\"button cmsmasters_post_read_more\" href=\"https:\/\/cirveproject.com\/fr\/interoperabilidad-conexion-espana-francia-portugal-proyecto-europeo-cirve\/\">Read More<\/a><\/footer><\/div><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13037\" class=\"cmsmasters_post_masonry post-13037 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es-fr tag-ciudad-del-transporte-de-murcia-fr tag-gic-es-fr tag-proyecto-europeo-cirve-fr tag-recarga-rapida-para-vehiculos-electricos-fr\" data-category=\"cirve-es-fr\">\r\n\t<div class=\"cmsmasters_post_cont\">\r\n\t\t<figure class=\"cmsmasters_img_wrap\"><a href=\"https:\/\/cirveproject.com\/fr\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/\" title=\"La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\" class=\"cmsmasters_img_link preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"360\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2020\/01\/punto-carga-Murcia-Veh\u00edculo-El\u00e9ctrico_CIRVE-project_-580x360.jpg\" class=\"full-width wp-post-image\" alt=\"La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\" title=\"La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\" \/><\/a><\/figure><div class=\"cmsmasters_post_cont_wrapper\"><div class=\"cmsmasters_post_info entry-meta\"><span class=\"cmsmasters_post_date\">On <abbr class=\"published\" title=\"janvier 7, 2020\"><span class=\"cmsmasters_day_mon\">janvier 07<\/span>, <span class=\"cmsmasters_year\">2020<\/span><\/abbr><abbr class=\"dn date updated\" title=\"janvier 7, 2020\">janvier 7, 2020<\/abbr><\/span><div class=\"cmsmasters_post_meta_info\"><span class=\"cmsmasters_comments cmsmasters_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/fr\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/#respond\" title=\"Comment on La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_likes cmsmasters_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13037); return false;\" id=\"cmsmastersLike-13037\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><\/div><\/div><div class=\"cmsmasters_post_info_bottom entry-meta\"><header class=\"cmsmasters_post_header entry-header\"><h3 class=\"cmsmasters_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/fr\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/\">La ciudad del transporte de Murcia estrena un punto de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos<\/a><\/h3><\/header><div class=\"cmsmasters_post_cont_info entry-meta\"><span class=\"cmsmasters_post_category\"><span>In<\/span><a href=\"https:\/\/cirveproject.com\/fr\/category\/cirve-es-fr\/\" class=\"cmsmasters_cat_color cmsmasters_cat_143\" rel=\"category tag\">Cirve ES<\/a><\/span><span class=\"cmsmasters_post_author\"><span>By<\/span><a href=\"https:\/\/cirveproject.com\/fr\/author\/aorenga_u8k3ghf9\/\" title=\"Posts by IMEDIA\" class=\"vcard author\"><span class=\"fn\" rel=\"author\">IMEDIA<\/span><\/a><\/span><\/div><div class=\"cmsmasters_post_content entry-content\">\n<p>Es v\u00e1lido para todos los modelos y costar\u00e1 0,45 euros el kw, que se pagar\u00e1n a trav\u00e9s de una app...<\/p>\n<\/div>\n<footer class=\"cmsmasters_post_footer entry-meta\"><a class=\"button cmsmasters_post_read_more\" href=\"https:\/\/cirveproject.com\/fr\/la-ciudad-del-transporte-de-murcia-estrena-un-punto-de-recarga-rapida-para-vehiculos-electricos\/\">Read More<\/a><\/footer><\/div><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13042\" class=\"cmsmasters_post_masonry post-13042 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es-fr tag-cirve-fr tag-endesa-es-fr tag-galp-fr tag-movilidad-fr tag-puntos-de-carga-rapida-vehiculo-electrico-fr\" data-category=\"cirve-es-fr\">\r\n\t<div class=\"cmsmasters_post_cont\">\r\n\t\t<figure class=\"cmsmasters_img_wrap\"><a href=\"https:\/\/cirveproject.com\/fr\/endesa-inaugura-punto-carga-rapida\/\" title=\"Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\" class=\"cmsmasters_img_link preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"360\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2019\/02\/Endesa-Inauguracion-Isla-Energia-580x360.jpg\" class=\"full-width wp-post-image\" alt=\"Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\" title=\"Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\" \/><\/a><\/figure><div class=\"cmsmasters_post_cont_wrapper\"><div class=\"cmsmasters_post_info entry-meta\"><span class=\"cmsmasters_post_date\">On <abbr class=\"published\" title=\"f\u00e9vrier 26, 2019\"><span class=\"cmsmasters_day_mon\">f\u00e9vrier 26<\/span>, <span class=\"cmsmasters_year\">2019<\/span><\/abbr><abbr class=\"dn date updated\" title=\"f\u00e9vrier 26, 2019\">f\u00e9vrier 26, 2019<\/abbr><\/span><div class=\"cmsmasters_post_meta_info\"><span class=\"cmsmasters_comments cmsmasters_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/fr\/endesa-inaugura-punto-carga-rapida\/#respond\" title=\"Comment on Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_likes cmsmasters_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13042); return false;\" id=\"cmsmastersLike-13042\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><\/div><\/div><div class=\"cmsmasters_post_info_bottom entry-meta\"><header class=\"cmsmasters_post_header entry-header\"><h3 class=\"cmsmasters_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/fr\/endesa-inaugura-punto-carga-rapida\/\">Endesa inaugura el primer punto de carga r\u00e1pida en una estaci\u00f3n de servicio de Galp<\/a><\/h3><\/header><div class=\"cmsmasters_post_cont_info entry-meta\"><span class=\"cmsmasters_post_category\"><span>In<\/span><a href=\"https:\/\/cirveproject.com\/fr\/category\/cirve-es-fr\/\" class=\"cmsmasters_cat_color cmsmasters_cat_143\" rel=\"category tag\">Cirve ES<\/a><\/span><span class=\"cmsmasters_post_author\"><span>By<\/span><a href=\"https:\/\/cirveproject.com\/fr\/author\/aorenga_u8k3ghf9\/\" title=\"Posts by IMEDIA\" class=\"vcard author\"><span class=\"fn\" rel=\"author\">IMEDIA<\/span><\/a><\/span><\/div><div class=\"cmsmasters_post_content entry-content\">\n<p>Endesa y Galp han llegado a un acuerdo para instalar 5 puntos de carga r\u00e1pida en estaciones de servicio de...<\/p>\n<\/div>\n<footer class=\"cmsmasters_post_footer entry-meta\"><a class=\"button cmsmasters_post_read_more\" href=\"https:\/\/cirveproject.com\/fr\/endesa-inaugura-punto-carga-rapida\/\">Read More<\/a><\/footer><\/div><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13045\" class=\"cmsmasters_post_masonry post-13045 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es-fr tag-euskotren-fr tag-ibil-fr tag-movilidad-electrica-fr tag-vehiculo-electrico-fr\" data-category=\"cirve-es-fr\">\r\n\t<div class=\"cmsmasters_post_cont\">\r\n\t\t<figure class=\"cmsmasters_img_wrap\"><a href=\"https:\/\/cirveproject.com\/fr\/euskotren-movilidad-electrica-ibil\/\" title=\"Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\" class=\"cmsmasters_img_link preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"360\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/12\/euskotren_IBIL-580x360.jpg\" class=\"full-width wp-post-image\" alt=\"Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\" title=\"Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\" \/><\/a><\/figure><div class=\"cmsmasters_post_cont_wrapper\"><div class=\"cmsmasters_post_info entry-meta\"><span class=\"cmsmasters_post_date\">On <abbr class=\"published\" title=\"d\u00e9cembre 31, 2018\"><span class=\"cmsmasters_day_mon\">d\u00e9cembre 31<\/span>, <span class=\"cmsmasters_year\">2018<\/span><\/abbr><abbr class=\"dn date updated\" title=\"d\u00e9cembre 31, 2018\">d\u00e9cembre 31, 2018<\/abbr><\/span><div class=\"cmsmasters_post_meta_info\"><span class=\"cmsmasters_comments cmsmasters_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/fr\/euskotren-movilidad-electrica-ibil\/#respond\" title=\"Comment on Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_likes cmsmasters_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13045); return false;\" id=\"cmsmastersLike-13045\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><\/div><\/div><div class=\"cmsmasters_post_info_bottom entry-meta\"><header class=\"cmsmasters_post_header entry-header\"><h3 class=\"cmsmasters_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/fr\/euskotren-movilidad-electrica-ibil\/\">Euskotren se conecta a la movilidad el\u00e9ctrica en 11 centros de trabajo de la mano de IBIL<\/a><\/h3><\/header><div class=\"cmsmasters_post_cont_info entry-meta\"><span class=\"cmsmasters_post_category\"><span>In<\/span><a href=\"https:\/\/cirveproject.com\/fr\/category\/cirve-es-fr\/\" class=\"cmsmasters_cat_color cmsmasters_cat_143\" rel=\"category tag\">Cirve ES<\/a><\/span><span class=\"cmsmasters_post_author\"><span>By<\/span><a href=\"https:\/\/cirveproject.com\/fr\/author\/aorenga_u8k3ghf9\/\" title=\"Posts by IMEDIA\" class=\"vcard author\"><span class=\"fn\" rel=\"author\">IMEDIA<\/span><\/a><\/span><\/div><div class=\"cmsmasters_post_content entry-content\">\n<p>IBIL, empresa l\u00edder en infraestructura, tecnolog\u00eda y servicios para la recarga de veh\u00edculos el\u00e9ctricos, ha sido la encargada de instalar...<\/p>\n<\/div>\n<footer class=\"cmsmasters_post_footer entry-meta\"><a class=\"button cmsmasters_post_read_more\" href=\"https:\/\/cirveproject.com\/fr\/euskotren-movilidad-electrica-ibil\/\">Read More<\/a><\/footer><\/div><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13048\" class=\"cmsmasters_post_masonry post-13048 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es-fr tag-bilbao-fr tag-coche-electrico-fr tag-ibil-fr tag-puntos-de-carga-rapida-vehiculo-electrico-bilbao-fr\" data-category=\"cirve-es-fr\">\r\n\t<div class=\"cmsmasters_post_cont\">\r\n\t\t<figure class=\"cmsmasters_img_wrap\"><a href=\"https:\/\/cirveproject.com\/fr\/ibil-tercer-punto-carga-rapida-bilbao\/\" title=\"IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\" class=\"cmsmasters_img_link preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"360\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/12\/IBIL-pone-en-funcionamiento-su-tercer-punto-de-carga-r\u00e1pida-en-la-Avenida-de-Sabino-Arana-Bilbao-580x360.jpg\" class=\"full-width wp-post-image\" alt=\"IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\" title=\"IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\" \/><\/a><\/figure><div class=\"cmsmasters_post_cont_wrapper\"><div class=\"cmsmasters_post_info entry-meta\"><span class=\"cmsmasters_post_date\">On <abbr class=\"published\" title=\"d\u00e9cembre 11, 2018\"><span class=\"cmsmasters_day_mon\">d\u00e9cembre 11<\/span>, <span class=\"cmsmasters_year\">2018<\/span><\/abbr><abbr class=\"dn date updated\" title=\"d\u00e9cembre 11, 2018\">d\u00e9cembre 11, 2018<\/abbr><\/span><div class=\"cmsmasters_post_meta_info\"><span class=\"cmsmasters_comments cmsmasters_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/fr\/ibil-tercer-punto-carga-rapida-bilbao\/#respond\" title=\"Comment on IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_likes cmsmasters_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13048); return false;\" id=\"cmsmastersLike-13048\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><\/div><\/div><div class=\"cmsmasters_post_info_bottom entry-meta\"><header class=\"cmsmasters_post_header entry-header\"><h3 class=\"cmsmasters_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/fr\/ibil-tercer-punto-carga-rapida-bilbao\/\">IBIL pone en funcionamiento su tercer punto de carga r\u00e1pida en la Avenida de Sabino Arana (Bilbao)<\/a><\/h3><\/header><div class=\"cmsmasters_post_cont_info entry-meta\"><span class=\"cmsmasters_post_category\"><span>In<\/span><a href=\"https:\/\/cirveproject.com\/fr\/category\/cirve-es-fr\/\" class=\"cmsmasters_cat_color cmsmasters_cat_143\" rel=\"category tag\">Cirve ES<\/a><\/span><span class=\"cmsmasters_post_author\"><span>By<\/span><a href=\"https:\/\/cirveproject.com\/fr\/author\/aorenga_u8k3ghf9\/\" title=\"Posts by IMEDIA\" class=\"vcard author\"><span class=\"fn\" rel=\"author\">IMEDIA<\/span><\/a><\/span><\/div><div class=\"cmsmasters_post_content entry-content\">\n<p>Es un servicio imprescindible para todos los veh\u00edculos el\u00e9ctricos del \u00e1rea metropolitana de Bilbao y Bilbao IBIL, empresa especializada en...<\/p>\n<\/div>\n<footer class=\"cmsmasters_post_footer entry-meta\"><a class=\"button cmsmasters_post_read_more\" href=\"https:\/\/cirveproject.com\/fr\/ibil-tercer-punto-carga-rapida-bilbao\/\">Read More<\/a><\/footer><\/div><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n\r\n<!--_________________________ Start Standard Article _________________________ -->\r\n\r\n<article id=\"post-13051\" class=\"cmsmasters_post_masonry post-13051 post type-post status-publish format-standard has-post-thumbnail hentry category-cirve-es-fr tag-endesa-fr tag-movilidad-sostenible-fr tag-puntos-de-recarga-vehiculo-fr tag-vehiculo-electrico-fr\" data-category=\"cirve-es-fr\">\r\n\t<div class=\"cmsmasters_post_cont\">\r\n\t\t<figure class=\"cmsmasters_img_wrap\"><a href=\"https:\/\/cirveproject.com\/fr\/endesa-puntos-recarga-vehiculos-electricos\/\" title=\"Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\" class=\"cmsmasters_img_link preloader\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"360\" src=\"https:\/\/cirveproject.com\/wp-content\/uploads\/2018\/11\/Endesa-instalara-puntos-de-recarga-vehiculo-electrico-580x360.jpg\" class=\"full-width wp-post-image\" alt=\"Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\" title=\"Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\" \/><\/a><\/figure><div class=\"cmsmasters_post_cont_wrapper\"><div class=\"cmsmasters_post_info entry-meta\"><span class=\"cmsmasters_post_date\">On <abbr class=\"published\" title=\"novembre 19, 2018\"><span class=\"cmsmasters_day_mon\">novembre 19<\/span>, <span class=\"cmsmasters_year\">2018<\/span><\/abbr><abbr class=\"dn date updated\" title=\"novembre 19, 2018\">novembre 19, 2018<\/abbr><\/span><div class=\"cmsmasters_post_meta_info\"><span class=\"cmsmasters_comments cmsmasters_post_comments\"><a class=\"cmsmasters_theme_icon_comment\" href=\"https:\/\/cirveproject.com\/fr\/endesa-puntos-recarga-vehiculos-electricos\/#respond\" title=\"Comment on Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os\"><span>0<\/span><\/a><\/span><span class=\"cmsmasters_likes cmsmasters_post_likes\"><a href=\"#\" onclick=\"cmsmasters_like(13051); return false;\" id=\"cmsmastersLike-13051\" class=\"cmsmastersLike cmsmasters_theme_icon_like\"><span>0<\/span><\/a><\/span><\/div><\/div><div class=\"cmsmasters_post_info_bottom entry-meta\"><header class=\"cmsmasters_post_header entry-header\"><h3 class=\"cmsmasters_post_title entry-title\"><a href=\"https:\/\/cirveproject.com\/fr\/endesa-puntos-recarga-vehiculos-electricos\/\">Endesa instalar\u00e1 m\u00e1s de 100.000 puntos de recarga para veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos 5 a\u00f1os<\/a><\/h3><\/header><div class=\"cmsmasters_post_cont_info entry-meta\"><span class=\"cmsmasters_post_category\"><span>In<\/span><a href=\"https:\/\/cirveproject.com\/fr\/category\/cirve-es-fr\/\" class=\"cmsmasters_cat_color cmsmasters_cat_143\" rel=\"category tag\">Cirve ES<\/a><\/span><span class=\"cmsmasters_post_author\"><span>By<\/span><a href=\"https:\/\/cirveproject.com\/fr\/author\/aorenga_u8k3ghf9\/\" title=\"Posts by IMEDIA\" class=\"vcard author\"><span class=\"fn\" rel=\"author\">IMEDIA<\/span><\/a><\/span><\/div><div class=\"cmsmasters_post_content entry-content\">\n<p>Durante el periodo del plan, Endesa X tiene previsto instalar m\u00e1s de 8.500 puntos de acceso p\u00fablico y\u00a0alrededor de 100.000...<\/p>\n<\/div>\n<footer class=\"cmsmasters_post_footer entry-meta\"><a class=\"button cmsmasters_post_read_more\" href=\"https:\/\/cirveproject.com\/fr\/endesa-puntos-recarga-vehiculos-electricos\/\">Read More<\/a><\/footer><\/div><\/div>\t<\/div>\r\n<\/article>\r\n<!--_________________________ Finish Standard Article _________________________ -->\r\n\r\n<\/div><div class=\"cmsmasters_wrap_more_posts cmsmasters_wrap_more_items\"><div class=\"cmsmasters_wrap_post_loader cmsmasters_wrap_items_loader\">\r\n\t\t\t\t\t<a href=\"javascript:void(0);\" class=\"cmsmasters_button cmsmasters_post_loader cmsmasters_items_loader\">\r\n\t\t\t\t\t\t<span>Load More Posts<\/span>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelles - CIRVE Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cirveproject.com\/fr\/nouvelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles - CIRVE Project\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cirveproject.com\/fr\/nouvelles\/\" \/>\n<meta property=\"og:site_name\" content=\"CIRVE Project\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-24T15:59:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CIRVEproject\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cirveproject.com\/fr\/nouvelles\/\",\"url\":\"https:\/\/cirveproject.com\/fr\/nouvelles\/\",\"name\":\"Nouvelles - CIRVE Project\",\"isPartOf\":{\"@id\":\"https:\/\/cirveproject.com\/#website\"},\"datePublished\":\"2017-06-12T08:58:26+00:00\",\"dateModified\":\"2020-02-24T15:59:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cirveproject.com\/fr\/nouvelles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cirveproject.com\/fr\/nouvelles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cirveproject.com\/fr\/nouvelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cirveproject.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cirveproject.com\/#website\",\"url\":\"https:\/\/cirveproject.com\/\",\"name\":\"CIRVE Project\",\"description\":\"Connecting the Iberian Peninsula with the other countries of the European Union is the mission of the CIRVE Project, whose acronym stands for \u201cIberian Corridors of Rapid Recharging Infrastructure for Electric Vehicles\u201d.\",\"publisher\":{\"@id\":\"https:\/\/cirveproject.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cirveproject.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cirveproject.com\/#organization\",\"name\":\"CIRVE Project\",\"url\":\"https:\/\/cirveproject.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png\",\"contentUrl\":\"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png\",\"width\":190,\"height\":65,\"caption\":\"CIRVE Project\"},\"image\":{\"@id\":\"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/CIRVEproject\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles - CIRVE Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cirveproject.com\/fr\/nouvelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles - CIRVE Project","og_url":"https:\/\/cirveproject.com\/fr\/nouvelles\/","og_site_name":"CIRVE Project","article_modified_time":"2020-02-24T15:59:03+00:00","twitter_card":"summary_large_image","twitter_site":"@CIRVEproject","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cirveproject.com\/fr\/nouvelles\/","url":"https:\/\/cirveproject.com\/fr\/nouvelles\/","name":"Nouvelles - CIRVE Project","isPartOf":{"@id":"https:\/\/cirveproject.com\/#website"},"datePublished":"2017-06-12T08:58:26+00:00","dateModified":"2020-02-24T15:59:03+00:00","breadcrumb":{"@id":"https:\/\/cirveproject.com\/fr\/nouvelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cirveproject.com\/fr\/nouvelles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cirveproject.com\/fr\/nouvelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cirveproject.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles"}]},{"@type":"WebSite","@id":"https:\/\/cirveproject.com\/#website","url":"https:\/\/cirveproject.com\/","name":"CIRVE Project","description":"Connecting the Iberian Peninsula with the other countries of the European Union is the mission of the CIRVE Project, whose acronym stands for \u201cIberian Corridors of Rapid Recharging Infrastructure for Electric Vehicles\u201d.","publisher":{"@id":"https:\/\/cirveproject.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cirveproject.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cirveproject.com\/#organization","name":"CIRVE Project","url":"https:\/\/cirveproject.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/","url":"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png","contentUrl":"http:\/\/cirveproject.com\/wp-content\/uploads\/2017\/07\/CIRVE_original_WEB.png","width":190,"height":65,"caption":"CIRVE Project"},"image":{"@id":"https:\/\/cirveproject.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/CIRVEproject"]}]}},"_links":{"self":[{"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/pages\/13146"}],"collection":[{"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/comments?post=13146"}],"version-history":[{"count":1,"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/pages\/13146\/revisions"}],"predecessor-version":[{"id":13147,"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/pages\/13146\/revisions\/13147"}],"wp:attachment":[{"href":"https:\/\/cirveproject.com\/fr\/wp-json\/wp\/v2\/media?parent=13146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}